{"id":6314,"date":"2019-02-14T22:17:28","date_gmt":"2019-02-14T22:17:28","guid":{"rendered":"http:\/\/www.promendoza.com\/?page_id=6314"},"modified":"2025-06-19T13:50:19","modified_gmt":"2025-06-19T16:50:19","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/www.promendoza.com\/es\/quienes-somos\/","title":{"rendered":"Qui\u00e9nes somos"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsms_row_6a573e7e48c0f3_48877001 .cmsms_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsms_row_6a573e7e48c0f3_48877001 .cmsms_row_outer_parent { \n\tpadding-bottom: 0px; \n} \n\n\r\n\t\t\t#cmsms_gallery_6a573e7e48c9a3_34680494 .cmsms_gallery {\r\n\t\t\t\tmargin:0 0 0 -10px;\r\n\t\t\t}\r\n\t\t\t\r\n\t\t\t#cmsms_gallery_6a573e7e48c9a3_34680494 .cmsms_gallery .cmsms_gallery_item {\r\n\t\t\t\tpadding:0 0 10px 10px;\r\n\t\t\t}\r\n\t\t \n#cmsms_row_6a573e7e48f7d5_61417391 .cmsms_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsms_row_6a573e7e48f7d5_61417391 .cmsms_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsms_heading_6a573e7e48fe85_96735822 { \n\ttext-align:left; \n\tmargin-top:35px; \n\tmargin-bottom:0px; \n} \n\n#cmsms_heading_6a573e7e48fe85_96735822 .cmsms_heading { \n\ttext-align:left; \n} \n\n#cmsms_heading_6a573e7e48fe85_96735822 .cmsms_heading, #cmsms_heading_6a573e7e48fe85_96735822 .cmsms_heading a { \n\tfont-weight:bold; \n\tfont-style:normal; \n} \n\n#cmsms_heading_6a573e7e48fe85_96735822 .cmsms_heading_divider { \n} \n\n \n#cmsms_row_6a573e7e48ffe9_76495869 .cmsms_row_outer_parent { \n\tpadding-top: 10px; \n} \n\n#cmsms_row_6a573e7e48ffe9_76495869 .cmsms_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsms_row_6a573e7e490b49_74804828 .cmsms_row_outer_parent { \n\tpadding-top: 10px; \n} \n\n#cmsms_row_6a573e7e490b49_74804828 .cmsms_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsms_tabs_list_item_6a573e7e491c59_80700025 a:hover,#cmsms_tabs_list_item_6a573e7e491c59_80700025 a:hover:before,#cmsms_tabs_list_item_6a573e7e491c59_80700025.current_tab a:before,#cmsms_tabs_list_item_6a573e7e491c59_80700025.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e4921a8_39596477 a:hover,#cmsms_tabs_list_item_6a573e7e4921a8_39596477 a:hover:before,#cmsms_tabs_list_item_6a573e7e4921a8_39596477.current_tab a:before,#cmsms_tabs_list_item_6a573e7e4921a8_39596477.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e492645_21148992 a:hover,#cmsms_tabs_list_item_6a573e7e492645_21148992 a:hover:before,#cmsms_tabs_list_item_6a573e7e492645_21148992.current_tab a:before,#cmsms_tabs_list_item_6a573e7e492645_21148992.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e492ab4_98305186 a:hover,#cmsms_tabs_list_item_6a573e7e492ab4_98305186 a:hover:before,#cmsms_tabs_list_item_6a573e7e492ab4_98305186.current_tab a:before,#cmsms_tabs_list_item_6a573e7e492ab4_98305186.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e492f00_83765207 a:hover,#cmsms_tabs_list_item_6a573e7e492f00_83765207 a:hover:before,#cmsms_tabs_list_item_6a573e7e492f00_83765207.current_tab a:before,#cmsms_tabs_list_item_6a573e7e492f00_83765207.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e493359_09872858 a:hover,#cmsms_tabs_list_item_6a573e7e493359_09872858 a:hover:before,#cmsms_tabs_list_item_6a573e7e493359_09872858.current_tab a:before,#cmsms_tabs_list_item_6a573e7e493359_09872858.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e4937a7_86986465 a:hover,#cmsms_tabs_list_item_6a573e7e4937a7_86986465 a:hover:before,#cmsms_tabs_list_item_6a573e7e4937a7_86986465.current_tab a:before,#cmsms_tabs_list_item_6a573e7e4937a7_86986465.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e493bf6_84304250 a:hover,#cmsms_tabs_list_item_6a573e7e493bf6_84304250 a:hover:before,#cmsms_tabs_list_item_6a573e7e493bf6_84304250.current_tab a:before,#cmsms_tabs_list_item_6a573e7e493bf6_84304250.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e494023_03111278 a:hover,#cmsms_tabs_list_item_6a573e7e494023_03111278 a:hover:before,#cmsms_tabs_list_item_6a573e7e494023_03111278.current_tab a:before,#cmsms_tabs_list_item_6a573e7e494023_03111278.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e494455_88350617 a:hover,#cmsms_tabs_list_item_6a573e7e494455_88350617 a:hover:before,#cmsms_tabs_list_item_6a573e7e494455_88350617.current_tab a:before,#cmsms_tabs_list_item_6a573e7e494455_88350617.current_tab a { \n\tcolor:#5b87ba;\n} \n\n#cmsms_tabs_list_item_6a573e7e494892_27808665 a:hover,#cmsms_tabs_list_item_6a573e7e494892_27808665 a:hover:before,#cmsms_tabs_list_item_6a573e7e494892_27808665.current_tab a:before,#cmsms_tabs_list_item_6a573e7e494892_27808665.current_tab a { \n\tcolor:#5b87ba;\n} \n<\/style><div id=\"cmsms_row_6a573e7e48c0f3_48877001\" class=\"cmsms_row cmsms_color_scheme_default\">\n<div class=\"cmsms_row_outer_parent\">\n<div class=\"cmsms_row_outer\">\n<div class=\"cmsms_row_inner\">\n<div class=\"cmsms_row_margin\">\n<div class=\"cmsms_column one_first\">\n<div id=\"cmsms_gallery_6a573e7e48c9a3_34680494\" class=\"cmsms_gallery_wrap\"><ul class=\"cmsms_gallery cmsms_1 cmsms_more_items_loader\"><li class=\"cmsms_gallery_item\"><figure><img width=\"1080\" height=\"383\" src=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019.jpg 1080w, https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019-300x106.jpg 300w, https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019-768x272.jpg 768w, https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019-1024x363.jpg 1024w, https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019-580x206.jpg 580w, https:\/\/www.promendoza.com\/wp-content\/uploads\/2019\/04\/quienes-somos-2019-820x291.jpg 820w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/figure><\/li><\/ul><script type=\"text\/javascript\">\r\n\t\t\tjQuery(document).ready(function () {\r\n\t\t\t\t(function ($) {\r\n\t\t\t\t\tif ($('#cmsms_gallery_6a573e7e48c9a3_34680494').find('.cmsms_gallery_item').length == '0') {\r\n\t\t\t\t\t\treturn false;\r\n\t\t\t\t\t}\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\tstartGallery( \r\n\t\t\t\t\t\t'6a573e7e48c9a3_34680494', \r\n\t\t\t\t\t\t'grid', \r\n\t\t\t\t\t\t'false', \r\n\t\t\t\t\t\t'false' \r\n\t\t\t\t\t);\r\n\t\t\t\t} )(jQuery);\r\n\t\t\t} );\r\n\t\t<\/script>\r\n\t\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsms_row_6a573e7e48f7d5_61417391\" class=\"cmsms_row cmsms_color_scheme_default\">\n<div class=\"cmsms_row_outer_parent\">\n<div class=\"cmsms_row_outer\">\n<div class=\"cmsms_row_inner\">\n<div class=\"cmsms_row_margin\">\n<div class=\"cmsms_column one_first\">\n\n<div id=\"cmsms_heading_6a573e7e48fe85_96735822\" class=\"cmsms_heading_wrap cmsms_heading_align_left\">\n\t<h4 class=\"cmsms_heading\">\u00bfQUI\u00c9NES SOMOS?<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsms_row_6a573e7e48ffe9_76495869\" class=\"cmsms_row cmsms_color_scheme_default\">\n<div class=\"cmsms_row_outer_parent\">\n<div class=\"cmsms_row_outer\">\n<div class=\"cmsms_row_inner\">\n<div class=\"cmsms_row_margin\">\n<div class=\"cmsms_column one_third\">\n<div class=\"cmsms_text\">\n<h6>MENDOZA PRODUCTIVA<\/h6>\n<p style=\"text-align: justify;\">Mendoza es una provincia productiva por naturaleza. Sus condiciones clim\u00e1ticas, su materia prima, los recursos humanos calificados, la inversi\u00f3n tecnol\u00f3gica y la infraestructura, la convierten en una regi\u00f3n atractiva y diversa. Alimentos procesados y org\u00e1nicos, frutas y hortalizas frescas, vinos, aceites de oliva, maquinarias, desarrollos tecnol\u00f3gicos y servicios integran su oferta exportable.<\/p>\n<\/div>\n<\/div>\n<div class=\"cmsms_column one_third\">\n<div class=\"cmsms_text\">\n<h6>FUNDACI\u00d3N PROMENDOZA<\/h6>\n<p style=\"text-align: justify;\">Para impulsar la internacionalizaci\u00f3n de la Provincia, desde 1996 Fundaci\u00f3n ProMendoza acompa\u00f1a a los empresarios mendocinos a posicionar sus productos y servicios en el mundo. Esta entidad p\u00fablico-privada es el resultado de la uni\u00f3n de esfuerzos de cuatro protagonistas relevantes de la econom\u00eda provincial: el Gobierno de Mendoza, la Uni\u00f3n Comercial e Industrial, la Bolsa de Comercio y la Federaci\u00f3n Econ\u00f3mica de Mendoza.<\/p>\n<\/div>\n<\/div>\n<div class=\"cmsms_column one_third\">\n<div class=\"cmsms_text\">\n<h6>\u00bfQU\u00c9 HACEMOS?<\/h6>\n<p style=\"text-align: justify;\">La Fundaci\u00f3n genera informaci\u00f3n estrat\u00e9gica, desarrolla acciones de promoci\u00f3n y herramientas para facilitar la exportaci\u00f3n tales como misiones y agendas comerciales, ferias internacionales, rondas inversas con importadores, entre otras.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, la Fundaci\u00f3n fomenta el crecimiento de las Pymes locales a trav\u00e9s de programas de desarrollo y capacitaci\u00f3n espec\u00edficos para responder a las diversas necesidades de los emprendimientos mendocinos.<\/p>\n<p>ProMendoza, junto al Ente Mendoza de Turismo, representan a Mendoza en la <a href=\"https:\/\/www.greatwinecapitals.com\" target=\"_blank\" rel=\"noopener noreferrer\">Red Global de las Grandes Capitales del Vino (GWC)<\/a>.<\/p>\n<p>Para mayor informaci\u00f3n escribinos a <a href=\"mailto:csuarez@promendoza.com\">csuarez@promendoza.com<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsms_row_6a573e7e490b49_74804828\" class=\"cmsms_row cmsms_color_scheme_default\">\n<div class=\"cmsms_row_outer_parent\">\n<div class=\"cmsms_row_outer\">\n<div class=\"cmsms_row_inner\">\n<div class=\"cmsms_row_margin\">\n<div class=\"cmsms_column one_first\">\n<div class=\"cmsms_text\">\n<h6>MEMORIAS INSTITUCIONALES<\/h6>\n<p>Pod\u00e9s conocer m\u00e1s de nuestro trabajo, accediendo a nuestras memorias institucionales:<\/p>\n<\/div>\n \n<div class=\"cmsms_tabs tabs_mode_tab\">\n<ul class=\"cmsms_tabs_list\">\n<li id=\"cmsms_tabs_list_item_6a573e7e491c59_80700025\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2024<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e4921a8_39596477\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2023<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e492645_21148992\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2022<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e492ab4_98305186\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2021<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e492f00_83765207\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2020<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e493359_09872858\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2019<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e4937a7_86986465\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2018<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e493bf6_84304250\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2017<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e494023_03111278\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2016<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e494455_88350617\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2015<\/span>\n<\/a>\n<\/li><li id=\"cmsms_tabs_list_item_6a573e7e494892_27808665\" class=\"cmsms_tabs_list_item\">\n<a href=\"#\" class=\"cmsms-icon-file-pdf\">\n<span>A\u00f1o 2014<\/span>\n<\/a>\n<\/li><\/ul>\n<div class=\"cmsms_tabs_wrap\">\n<div id=\"cmsms_tab_6a573e7e491c59_80700025\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2025\/06\/Memoria-Fundacion-ProMendoza-2024-FINAL.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2024<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e4921a8_39596477\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2023.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2023<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e492645_21148992\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2022.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2022<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e492ab4_98305186\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2021.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2021<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e492f00_83765207\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2020<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e493359_09872858\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2019.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2019<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e4937a7_86986465\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2018.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2018<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e493bf6_84304250\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2017.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2017<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e494023_03111278\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2016.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2016<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e494455_88350617\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2015.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2015<\/a><\/p>\n<\/div>\n<\/div><div id=\"cmsms_tab_6a573e7e494892_27808665\" class=\"cmsms_tab\">\n<div class=\"cmsms_tab_inner\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.promendoza.com\/wp-content\/uploads\/2024\/10\/Memoria-2014.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar a\u00f1o 2014<\/a><\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/pages\/6314"}],"collection":[{"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/comments?post=6314"}],"version-history":[{"count":48,"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/pages\/6314\/revisions"}],"predecessor-version":[{"id":15906,"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/pages\/6314\/revisions\/15906"}],"wp:attachment":[{"href":"https:\/\/www.promendoza.com\/es\/wp-json\/wp\/v2\/media?parent=6314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}